{"id":76979,"date":"2026-05-11T01:10:58","date_gmt":"2026-05-10T23:10:58","guid":{"rendered":"https:\/\/www.adfc-wiesbaden.de\/?p=76979"},"modified":"2026-05-11T01:10:58","modified_gmt":"2026-05-10T23:10:58","slug":"nachhaltigkeitstag-in-oestrich-am-21-juni-2026","status":"publish","type":"post","link":"https:\/\/www.adfc-wiesbaden.de\/fa\/2026\/05\/veranstaltungen\/nachhaltigkeitstag-in-oestrich-am-21-juni-2026\/","title":{"rendered":"Nachhaltigkeitstag in Oestrich am 21. Juni 2026"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-76979\" data-postid=\"76979\" class=\"themify_builder_content themify_builder_content-76979 themify_builder tf_clear\">\n                    <div  data-lazy=\"1\" class=\"module_row themify_builder_row tb_vvxr258 tb_first tf_w\">\n                        <div class=\"row_inner col_align_top tb_col_count_1 tf_box tf_rel\">\n                        <div  data-lazy=\"1\" class=\"module_column tb-column col-full tb_qlsn258 first\">\n                    <!-- module image -->\n<div  class=\"module module-image tb_vjg0943 image-top   tf_mw tb_gs2677162d\" data-lazy=\"1\">\n        <div class=\"image-wrap tf_rel tf_mw\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"399\" src=\"https:\/\/www.adfc-wiesbaden.de\/wp-content\/uploads\/2026\/05\/ankuendigung-nachhaltigkeitstag-oestrich-2026.jpg\" class=\"wp-post-image wp-image-77183\" title=\"Werbebanner Nachhaltigkeitstag Oestrich 2026\" alt=\"Werbebanner Nachhaltigkeitstag Oestrich 2026\" srcset=\"https:\/\/www.adfc-wiesbaden.de\/wp-content\/uploads\/2026\/05\/ankuendigung-nachhaltigkeitstag-oestrich-2026.jpg 780w, https:\/\/www.adfc-wiesbaden.de\/wp-content\/uploads\/2026\/05\/ankuendigung-nachhaltigkeitstag-oestrich-2026-700x358.jpg 700w, https:\/\/www.adfc-wiesbaden.de\/wp-content\/uploads\/2026\/05\/ankuendigung-nachhaltigkeitstag-oestrich-2026-200x102.jpg 200w, https:\/\/www.adfc-wiesbaden.de\/wp-content\/uploads\/2026\/05\/ankuendigung-nachhaltigkeitstag-oestrich-2026-768x393.jpg 768w, https:\/\/www.adfc-wiesbaden.de\/wp-content\/uploads\/2026\/05\/ankuendigung-nachhaltigkeitstag-oestrich-2026-18x9.jpg 18w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/>    \n        <\/div>\n    <!-- \/image-wrap -->\n    \n        <div class=\"image-content\">\n                    <h3 class=\"image-title\">\n                                    Werbebanner Nachhaltigkeitstag Oestrich 2026                            <\/h3>\n                    <\/div>\n    <!-- \/image-content -->\n        <\/div>\n<!-- \/module image --><!-- module text -->\n<div  class=\"module module-text tb_6p6f165    tb_gs678604\" data-lazy=\"1\">\n        <div  class=\"tb_text_wrap\">\n        <h1>Nachhaltigkeitstag in Oestrich: Der ADFC ist dabei!<\/h1>\n<p><strong>Am 21. Juni 2026, ab 11:00 Uhr, triffst Du uns beim Nachhaltigkeitstag in Oestrich. Dort findet auch eine Fahrradb\u00f6rse statt.\u00a0<\/strong><\/p>\n<p>Der Nachhaltigkeitstag bietet Ideen, Austausch und alles rund ums klimafreundliche Radfahren. Zudem organisiert die\u00a0Stadt Oestrich eine Fahrradb\u00f6rse f\u00fcr Kauf und Verkauf gebrauchter Fahrr\u00e4der oder Zubeh\u00f6r: Es gibt weder\u00a0 Geb\u00fchren noch ist eine Anmeldung notwendig. Einfach Fahrrad mitbringen, einen Platz suchen und Preisschild anbringen. K\u00e4ufer k\u00f6nnen einfach kommen, nach geeigneten R\u00e4dern oder Zubeh\u00f6r suchen, Probe fahren und kaufen.<\/p>\n<p>Aber auch andere Themenbereiche wie Gesundheit und Wohlbefinden, Umwelt\/Klima\/Energie, nachhaltiger Konsum und alternative Mobilit\u00e4tsformen werden auf dem Nachhaltigkeitstag vertreten sein. Eine bunte Mischung aus Infost\u00e4nden, Gewinnspielen und Mitmachaktionen f\u00fcr Gro\u00df und Klein machen den Nachhaltigkeitstag am Tag der Sommersonnenwende, zu einem attraktiven Ausflugsziel f\u00fcr die ganze Familie.<\/p>\n<p>Diese und viele weitere Informationen findest Du <a href=\"http:\/\/www.oestrich-winkel.de\/nachhaltigkeit\">hier<\/a>! Komm&#8216; vorbei!<\/p>\n<p>\u00a0<\/p>    <\/div>\n<\/div>\n<!-- \/module text -->        <\/div>\n                        <\/div>\n        <\/div>\n        <\/div>\n<!--\/themify_builder_content-->\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>ADFC im Rheingau: Am 21. Juni 2026, ab 11 Uhr, triffst Du uns beim Nachhaltigkeitstag in Oestrich. Dort findet auch eine Fahrradb\u00f6rse statt.<\/p>","protected":false},"author":60,"featured_media":74089,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"Nachrichten-Seite.php","format":"standard","meta":{"footnotes":""},"categories":[953,804],"tags":[853,857,807],"class_list":["post-76979","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rheingau","category-veranstaltungen","tag-fahrradboerse","tag-rheingau","tag-veranstaltung","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"builder_content":"<img src=\"https:\/\/www.adfc-wiesbaden.de\/wp-content\/uploads\/2026\/05\/ankuendigung-nachhaltigkeitstag-oestrich-2026.jpg\" title=\"Werbebanner Nachhaltigkeitstag Oestrich 2026\" alt=\"Werbebanner Nachhaltigkeitstag Oestrich 2026\" srcset=\"https:\/\/www.adfc-wiesbaden.de\/wp-content\/uploads\/2026\/05\/ankuendigung-nachhaltigkeitstag-oestrich-2026.jpg 780w, https:\/\/www.adfc-wiesbaden.de\/wp-content\/uploads\/2026\/05\/ankuendigung-nachhaltigkeitstag-oestrich-2026-700x358.jpg 700w, https:\/\/www.adfc-wiesbaden.de\/wp-content\/uploads\/2026\/05\/ankuendigung-nachhaltigkeitstag-oestrich-2026-200x102.jpg 200w, https:\/\/www.adfc-wiesbaden.de\/wp-content\/uploads\/2026\/05\/ankuendigung-nachhaltigkeitstag-oestrich-2026-768x393.jpg 768w, https:\/\/www.adfc-wiesbaden.de\/wp-content\/uploads\/2026\/05\/ankuendigung-nachhaltigkeitstag-oestrich-2026-18x9.jpg 18w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/> <h3> Werbebanner Nachhaltigkeitstag Oestrich 2026 <\/h3>\n<h1>Nachhaltigkeitstag in Oestrich: Der ADFC ist dabei!<\/h1> <p><strong>Am 21. Juni 2026, ab 11:00 Uhr, triffst Du uns beim Nachhaltigkeitstag in Oestrich. Dort findet auch eine Fahrradb\u00f6rse statt.\u00a0<\/strong><\/p> <p>Der Nachhaltigkeitstag bietet Ideen, Austausch und alles rund ums klimafreundliche Radfahren. Zudem organisiert die\u00a0Stadt Oestrich eine Fahrradb\u00f6rse f\u00fcr Kauf und Verkauf gebrauchter Fahrr\u00e4der oder Zubeh\u00f6r: Es gibt weder\u00a0 Geb\u00fchren noch ist eine Anmeldung notwendig. Einfach Fahrrad mitbringen, einen Platz suchen und Preisschild anbringen. K\u00e4ufer k\u00f6nnen einfach kommen, nach geeigneten R\u00e4dern oder Zubeh\u00f6r suchen, Probe fahren und kaufen.<\/p> <p>Aber auch andere Themenbereiche wie Gesundheit und Wohlbefinden, Umwelt\/Klima\/Energie, nachhaltiger Konsum und alternative Mobilit\u00e4tsformen werden auf dem Nachhaltigkeitstag vertreten sein. Eine bunte Mischung aus Infost\u00e4nden, Gewinnspielen und Mitmachaktionen f\u00fcr Gro\u00df und Klein machen den Nachhaltigkeitstag am Tag der Sommersonnenwende, zu einem attraktiven Ausflugsziel f\u00fcr die ganze Familie.<\/p> <p>Diese und viele weitere Informationen findest Du <a href=\"http:\/\/www.oestrich-winkel.de\/nachhaltigkeit\">hier<\/a>! Komm' vorbei!<\/p> <p>\u00a0<\/p>","_links":{"self":[{"href":"https:\/\/www.adfc-wiesbaden.de\/fa\/wp-json\/wp\/v2\/posts\/76979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adfc-wiesbaden.de\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adfc-wiesbaden.de\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adfc-wiesbaden.de\/fa\/wp-json\/wp\/v2\/users\/60"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adfc-wiesbaden.de\/fa\/wp-json\/wp\/v2\/comments?post=76979"}],"version-history":[{"count":25,"href":"https:\/\/www.adfc-wiesbaden.de\/fa\/wp-json\/wp\/v2\/posts\/76979\/revisions"}],"predecessor-version":[{"id":77196,"href":"https:\/\/www.adfc-wiesbaden.de\/fa\/wp-json\/wp\/v2\/posts\/76979\/revisions\/77196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adfc-wiesbaden.de\/fa\/wp-json\/wp\/v2\/media\/74089"}],"wp:attachment":[{"href":"https:\/\/www.adfc-wiesbaden.de\/fa\/wp-json\/wp\/v2\/media?parent=76979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adfc-wiesbaden.de\/fa\/wp-json\/wp\/v2\/categories?post=76979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adfc-wiesbaden.de\/fa\/wp-json\/wp\/v2\/tags?post=76979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}